{"id":6993,"date":"2019-05-31T12:29:03","date_gmt":"2019-05-31T10:29:03","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=6993"},"modified":"2019-05-31T12:29:03","modified_gmt":"2019-05-31T10:29:03","slug":"fattore-di-sporcamento-negli-scambiatori-di-calore","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/","title":{"rendered":"Fattore di sporcamento negli scambiatori di calore"},"content":{"rendered":"<p>Parliamo ancora di <a href=\"https:\/\/www.tempco.it\/soluzioni\/scambiatori-di-calore\/\" target=\"_blank\" rel=\"noopener\"><strong>scambiatori di calore<\/strong><\/a>, e nello specifico di <a href=\"https:\/\/www.tempco.it\/blog\/3145\/sporcamento-fouling-e-sedimentazione-negli-scambiatori-di-calore\/\" target=\"_blank\" rel=\"noopener\"><strong>fouling factor<\/strong><\/a>, o fattore di sporcamento in uno scambiatore. L\u2019argomento del nuovo video sul <a href=\"https:\/\/youtube.com\/c\/TempcoItalia\" target=\"_blank\" rel=\"noopener\">Canale Youtube Tempco<\/a> \u00e8 molto rilevante per garantire l\u2019<strong>efficienza di scambio termico<\/strong> negli scambiatori, e ricevo spesso al riguardo molte domande. I fluidi all\u2019interno degli scambiatori possono infatti con il tempo creare dei depositi sulle pareti di scambio termico, diminuendo l\u2019efficienza dello scambiatore.<\/p>\n<p>Il <strong>fouling factor<\/strong> \u00e8 quindi sostanzialmente un <a href=\"https:\/\/www.tempco.it\/wp-content\/uploads\/2012\/12\/Fattori-di-sporcamento.pdf\" target=\"_blank\" rel=\"noopener\">coefficiente di sovradimensionamento<\/a> che viene applicato nella progettazione degli <a href=\"https:\/\/www.tempco.it\/blog\/6671\/funzionamento-di-uno-scambiatore-a-piastre-tempco-video\/\" target=\"_blank\" rel=\"noopener\">scambiatori di calore<\/a>. In pratica, in progettazione viene previsto un margine superiore nel dimensionamento dello scambiatore, che serve a contrastare la perdita in efficienza di scambio termico dovuta a sporcamento delle superfici di trasferimento termico.<\/p>\n<p><iframe loading=\"lazy\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/bJfg-xKKZN4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Il calcolo del coefficiente dipende dal tipo di moti che avvengono all\u2019interno dello scambiatore, che influiscono direttamente sulla quantit\u00e0 di <strong>particelle che possono depositarsi sulle superfici di scambio<\/strong>. Il fattore di sporcamento varia quindi a seconda della tipologia di scambiatore coinvolta, che si tratti di uno <a href=\"https:\/\/www.tempco.it\/soluzioni\/scambiatori-di-calore\/fascio-tubiero\/\" target=\"_blank\" rel=\"noopener\"><strong>scambiatore a fascio tubiero<\/strong><\/a>, a piastre o altro ancora. I valori di <a href=\"https:\/\/www.tempco.it\/blog\/54\/fouling-factor-negli-scambiatori-a-piastre\/\" target=\"_blank\" rel=\"noopener\">fouling factor in uno scambiatore a piastre<\/a> sono in particolare dieci volte inferiori rispetto a quelli validi per uno scambiatore a fascio tubiero, in quanto all\u2019interno di uno scambiatore a piastre i <strong>moti dei fluidi sono molto pi\u00f9 turbolenti<\/strong>.<\/p>\n<p>Il <a href=\"https:\/\/www.tempco.it\/blog\/3268\/velocita-dei-fluidi-negli-scambiatori-di-calore\/\" target=\"_blank\" rel=\"noopener\"><strong>moto turbolento dei fluidi<\/strong><\/a> in uno scambiatore a piastre trasporta infatti con s\u00e9 le particelle che potrebbero depositarsi sulle superfici di scambio, richiedendo pertanto un inferiore coefficiente di sovradimensionamento dello scambiatore. Altra ragione \u00e8 legata alla costruzione stessa del tipo di scambiatore: uno <a href=\"https:\/\/www.tempco.it\/blog\/6755\/recupero-fumi-in-cogenerazione-e-scambiatori-a-fascio-tubiero\/\" target=\"_blank\" rel=\"noopener\">scambiatore a fascio tubiero<\/a> una volta costruito non pu\u00f2 essere ampliato, mentre uno scambiatore a piastre consente di <strong>variare e aumentare il numero di piastre<\/strong> all\u2019occorrenza, potendo quindi intervenire in caso di perdita di efficienza di scambio di calore dovuta ad esempio a <strong><a href=\"https:\/\/www.tempco.it\/blog\/5577\/free-flow-scambiatori-per-fluidi-sporchi\/\" target=\"_blank\" rel=\"noopener\">fluidi sporchi<\/a><\/strong> o variazioni nelle condizioni di progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Fouling factor, o fattore di sporcamento, negli scambiatori di calore consiste in un coefficiente di sovradimensionamento dello scambiatore per garantire sempre la massima efficienza di scambio termico.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[93,42,40,13,111,49,68,9,51],"tags":[644,1761,1763,483,1762,1531,118,133,528,117,116,122,1543,1764,1765,206],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fattore di sporcamento negli scambiatori di calore - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fattore di sporcamento negli scambiatori di calore - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Il Fouling factor, o fattore di sporcamento, negli scambiatori di calore consiste in un coefficiente di sovradimensionamento dello scambiatore per garantire sempre la massima efficienza di scambio termico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-31T10:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"317\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Zambelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Zambelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\"},\"author\":{\"name\":\"Marco Zambelli\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\"},\"headline\":\"Fattore di sporcamento negli scambiatori di calore\",\"datePublished\":\"2019-05-31T10:29:03+00:00\",\"dateModified\":\"2019-05-31T10:29:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\"},\"wordCount\":325,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"keywords\":[\"efficienza termica\",\"fattore di sporcamento\",\"fluidi sporchi\",\"fouling factor\",\"moto dei fluidi\",\"moto turbolento\",\"raffreddamento\",\"riscaldamento\",\"scambiatori a fascio tubiero\",\"scambiatori a piastre\",\"scambiatori di calore\",\"scambio termico\",\"solid temperature\",\"sovradimensionamento\",\"superficie di scambio termico\",\"trasferimento di calore\"],\"articleSection\":[\"calcolo di uno scambiatore di calore\",\"Fouling factor\",\"Lavaggio\",\"Manutenzione\",\"saldobrasati\",\"Scambiatori a piastre\",\"Scambiatori ad immersione\",\"Scambiatori di calore\",\"Scambiatori saldati\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\",\"name\":\"Fattore di sporcamento negli scambiatori di calore - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2019-05-31T10:29:03+00:00\",\"dateModified\":\"2019-05-31T10:29:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fattore di sporcamento negli scambiatori di calore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\",\"name\":\"Marco Zambelli\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fattore di sporcamento negli scambiatori di calore - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/","og_locale":"it_IT","og_type":"article","og_title":"Fattore di sporcamento negli scambiatori di calore - Tempco Blog","og_description":"Il Fouling factor, o fattore di sporcamento, negli scambiatori di calore consiste in un coefficiente di sovradimensionamento dello scambiatore per garantire sempre la massima efficienza di scambio termico.","og_url":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2019-05-31T10:29:03+00:00","og_image":[{"width":317,"height":317,"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","type":"image\/jpeg"}],"author":"Marco Zambelli","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Marco Zambelli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/"},"author":{"name":"Marco Zambelli","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4"},"headline":"Fattore di sporcamento negli scambiatori di calore","datePublished":"2019-05-31T10:29:03+00:00","dateModified":"2019-05-31T10:29:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/"},"wordCount":325,"commentCount":1,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"keywords":["efficienza termica","fattore di sporcamento","fluidi sporchi","fouling factor","moto dei fluidi","moto turbolento","raffreddamento","riscaldamento","scambiatori a fascio tubiero","scambiatori a piastre","scambiatori di calore","scambio termico","solid temperature","sovradimensionamento","superficie di scambio termico","trasferimento di calore"],"articleSection":["calcolo di uno scambiatore di calore","Fouling factor","Lavaggio","Manutenzione","saldobrasati","Scambiatori a piastre","Scambiatori ad immersione","Scambiatori di calore","Scambiatori saldati"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/","url":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/","name":"Fattore di sporcamento negli scambiatori di calore - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2019-05-31T10:29:03+00:00","dateModified":"2019-05-31T10:29:03+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/6993\/fattore-di-sporcamento-negli-scambiatori-di-calore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Fattore di sporcamento negli scambiatori di calore"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4","name":"Marco Zambelli"}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6993"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=6993"}],"version-history":[{"count":2,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6993\/revisions"}],"predecessor-version":[{"id":7001,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6993\/revisions\/7001"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=6993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=6993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=6993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}