{"id":6862,"date":"2019-03-22T13:28:24","date_gmt":"2019-03-22T12:28:24","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=6862"},"modified":"2019-03-22T13:28:24","modified_gmt":"2019-03-22T12:28:24","slug":"acqua-che-bolle-in-pentola-e-pitting-negli-scambiatori","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/6862\/acqua-che-bolle-in-pentola-e-pitting-negli-scambiatori\/","title":{"rendered":"Acqua che bolle in pentola e pitting negli scambiatori"},"content":{"rendered":"<p>Partendo da una domanda dal sapore \u2018culinario\u2019, cogliamo lo spunto per parlare di <strong><a href=\"https:\/\/www.tempco.it\/blog\/1869\/corrosione-o-erosione\/\" target=\"_blank\" rel=\"noopener\">pitting negli scambiatori a piastre<\/a><\/strong>, effetto noto anche come <strong>vaiolatura<\/strong>. E\u2019 infatti davvero molto illuminante la risposta che viene data a <a href=\"https:\/\/it.quora.com\/Il-sale-che-si-aggiunge-allacqua-per-cucinare-la-pasta-va-messo-quando-lacqua-bolle-o-prima\/answer\/Alessandro-Fais?ch=99&amp;share=86518e98&amp;srid=xzcoq\" target=\"_blank\" rel=\"noopener\">questo link<\/a> al quesito se in una pentola per cucinare la pasta sia meglio aggiungere il sale all\u2019acqua quando bolle o prima. La pratica corretta \u00e8 aggiungere il sale a bollore in corso, in quanto le bolle che salgono impediscono al sale di depositarsi sul fondo, dove a contatto con il metallo della pentola assorbe il calore pi\u00f9 rapidamente dell\u2019acqua, in quanto grani solidi, creando un\u2019area di contatto tra sale, acqua e metallo molto corrosiva per la pentola.<\/p>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-6864\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile.jpg\" alt=\"pitting da cloruri acciaio inossidabile\" width=\"584\" height=\"439\" srcset=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile.jpg 1020w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile-300x225.jpg 300w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile-768x576.jpg 768w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>Il <strong>pitting<\/strong> \u00e8 il risultato, ovvero piccole intaccature che con il tempo deteriorano la superficie del metallo scavando dei piccoli buchi. L&#8217;esempio del sale grosso nell\u2019acqua in cucina rende bene l&#8217;idea di come avviene il <a href=\"https:\/\/www.tempco.it\/blog\/1189\/resistenza-alla-corrosione-da-cloruri\/\" target=\"_blank\" rel=\"noopener\"><strong>pitting da cloruri<\/strong><\/a> con qualcosa che tutti conosciamo per pratica quotidiana. Lo stesso fenomeno lo osserviamo sulle <a href=\"https:\/\/www.tempco.it\/soluzioni\/scambiatori-di-calore\/\" target=\"_blank\" rel=\"noopener\"><strong>piastre degli scambiatori di calore<\/strong><\/a>, quando in presenza di concentrazioni localizzate di <a href=\"https:\/\/www.tempco.it\/blog\/4618\/corrosione-da-cloruri-negli-acciaio-inossidabili\/\" target=\"_blank\" rel=\"noopener\">elementi corrosivi<\/a> (cloruri o altro) avviene la perforazione delle piastre.<\/p>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-piastre-scambiatori-di-calore.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-6866\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-piastre-scambiatori-di-calore.jpg\" alt=\"pitting scambiatori di calore a piastre\" width=\"498\" height=\"373\" srcset=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-piastre-scambiatori-di-calore.jpg 983w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-piastre-scambiatori-di-calore-300x225.jpg 300w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-piastre-scambiatori-di-calore-768x576.jpg 768w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/a><\/p>\n<p>Facciamo un esempio con <a href=\"https:\/\/www.tempco.it\/blog\/5712\/ossidazione-anodica-dellalluminio-1\/\" target=\"_blank\" rel=\"noopener\">impianti di ossidazione anodica<\/a>.<br \/>\nIl fluido coinvolto in questo caso \u00e8 <strong>acido solforico<\/strong> in percentuali tali che l&#8217;acciaio inox <strong>AISI 316<\/strong> \u00e8 pi\u00f9 che sufficiente per resistere chimicamente all&#8217;aggressione. Nella <strong>zona dei bocchelli<\/strong> accade per\u00f2 che ad impianto fermo ci sia un ristagno di prodotto, con effetto di concentrazione dell&#8217;acido, che a lungo (o medio) termine provoca il tipico pitting e quindi la <strong>perforazione per corrosione delle piastre<\/strong>.<\/p>\n<p>Per tale motivo in applicazioni come questa e analoghe \u00e8 preferibile <a href=\"https:\/\/www.tempco.it\/blog\/285\/scambiatori-di-calore-a-piastre-i-materiali-delle-piastre\/\" target=\"_blank\" rel=\"noopener\">selezionare un materiale pi\u00f9 resistente<\/a>, come l&#8217;<strong>AVESTA 254 SMO<\/strong>, un tipo di acciaio inossidabile austenitico ad alto contenuto di molibdeno che offre nello specifico una elevata resistenza a corrosione e pitting.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrosione e pitting da cloruri in concentrazione con esposizione ad alte temperature possono portare facilmente alla perforazione delle piastre negli scambiatori di calore. <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[25,5,49,9],"tags":[936,1115,419,1637,1633,239,1515,436,304,1636,1632,117,116,1635,1634],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Corrosione e pitting da cloruri in concentrazione con esposizione ad alte temperature possono portare facilmente alla perforazione delle piastre negli scambiatori di calore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-22T12:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile.jpg\" \/>\n<meta name=\"author\" content=\"Marco Zambelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Zambelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\"},\"author\":{\"name\":\"Marco Zambelli\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\"},\"headline\":\"Acqua che bolle in pentola e pitting negli scambiatori\",\"datePublished\":\"2019-03-22T12:28:24+00:00\",\"dateModified\":\"2019-03-22T12:28:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\"},\"wordCount\":306,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"keywords\":[\"acciaio inossidabile\",\"acido solforico\",\"AISI 316\",\"AVESTA 254 SMO\",\"cloruri\",\"corrosione\",\"inox\",\"manutenzione\",\"ossidazione anodica\",\"perforazione piastre\",\"pitting\",\"scambiatori a piastre\",\"scambiatori di calore\",\"scelta materiali\",\"vaiolatura\"],\"articleSection\":[\"Corrosione\",\"Riscaldamento\",\"Scambiatori a piastre\",\"Scambiatori di calore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\",\"name\":\"Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2019-03-22T12:28:24+00:00\",\"dateModified\":\"2019-03-22T12:28:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acqua che bolle in pentola e pitting negli scambiatori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\",\"name\":\"Marco Zambelli\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/","og_locale":"it_IT","og_type":"article","og_title":"Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog","og_description":"Corrosione e pitting da cloruri in concentrazione con esposizione ad alte temperature possono portare facilmente alla perforazione delle piastre negli scambiatori di calore.","og_url":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2019-03-22T12:28:24+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2019\/03\/pitting-da-cloruri-acciaio-inossidabile.jpg"}],"author":"Marco Zambelli","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Marco Zambelli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/"},"author":{"name":"Marco Zambelli","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4"},"headline":"Acqua che bolle in pentola e pitting negli scambiatori","datePublished":"2019-03-22T12:28:24+00:00","dateModified":"2019-03-22T12:28:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/"},"wordCount":306,"commentCount":2,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"keywords":["acciaio inossidabile","acido solforico","AISI 316","AVESTA 254 SMO","cloruri","corrosione","inox","manutenzione","ossidazione anodica","perforazione piastre","pitting","scambiatori a piastre","scambiatori di calore","scelta materiali","vaiolatura"],"articleSection":["Corrosione","Riscaldamento","Scambiatori a piastre","Scambiatori di calore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/","url":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/","name":"Acqua che bolle in pentola e pitting negli scambiatori - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2019-03-22T12:28:24+00:00","dateModified":"2019-03-22T12:28:24+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/en\/6869\/boiling-water-in-a-pot-and-pitting-in-plate-heat-exchangers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Acqua che bolle in pentola e pitting negli scambiatori"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4","name":"Marco Zambelli"}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6862"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=6862"}],"version-history":[{"count":2,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6862\/revisions"}],"predecessor-version":[{"id":6868,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/6862\/revisions\/6868"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=6862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=6862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=6862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}