{"id":3647,"date":"2012-07-02T10:00:15","date_gmt":"2012-07-02T08:00:15","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=3647"},"modified":"2012-06-22T09:31:31","modified_gmt":"2012-06-22T07:31:31","slug":"tabella-valori-di-temperatura-pressione-del-vapore-acqueo","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/","title":{"rendered":"Tabella valori di temperatura-pressione del Vapore acqueo"},"content":{"rendered":"<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2012\/06\/Tabella-valori-di-temperatura-pressione-del-Vapore-acqueo.pdf\">Tabella valori di temperatura-pressione del Vapore acqueo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tabella valori di temperatura-pressione del Vapore acqueo<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Tabella valori di temperatura-pressione del Vapore acqueo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-02T08:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-22T07:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"317\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S. Pellucchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"S. Pellucchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\"},\"author\":{\"name\":\"S. Pellucchi\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/0bf1a6356091f7c7a2b8b0e001d48a09\"},\"headline\":\"Tabella valori di temperatura-pressione del Vapore acqueo\",\"datePublished\":\"2012-07-02T08:00:15+00:00\",\"dateModified\":\"2012-06-22T07:31:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\"},\"wordCount\":14,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"articleSection\":[\"Data sheet\",\"Glossary\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\",\"name\":\"Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2012-07-02T08:00:15+00:00\",\"dateModified\":\"2012-06-22T07:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tabella valori di temperatura-pressione del Vapore acqueo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/0bf1a6356091f7c7a2b8b0e001d48a09\",\"name\":\"S. Pellucchi\",\"sameAs\":[\"http:\/\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/","og_locale":"it_IT","og_type":"article","og_title":"Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog","og_description":"Tabella valori di temperatura-pressione del Vapore acqueo","og_url":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2012-07-02T08:00:15+00:00","article_modified_time":"2012-06-22T07:31:31+00:00","og_image":[{"width":317,"height":317,"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","type":"image\/jpeg"}],"author":"S. Pellucchi","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"S. Pellucchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/"},"author":{"name":"S. Pellucchi","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/0bf1a6356091f7c7a2b8b0e001d48a09"},"headline":"Tabella valori di temperatura-pressione del Vapore acqueo","datePublished":"2012-07-02T08:00:15+00:00","dateModified":"2012-06-22T07:31:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/"},"wordCount":14,"commentCount":0,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"articleSection":["Data sheet","Glossary"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/","url":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/","name":"Tabella valori di temperatura-pressione del Vapore acqueo - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2012-07-02T08:00:15+00:00","dateModified":"2012-06-22T07:31:31+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/3647\/tabella-valori-di-temperatura-pressione-del-vapore-acqueo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Tabella valori di temperatura-pressione del Vapore acqueo"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/0bf1a6356091f7c7a2b8b0e001d48a09","name":"S. Pellucchi","sameAs":["http:\/\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/3647"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=3647"}],"version-history":[{"count":2,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/3647\/revisions"}],"predecessor-version":[{"id":3655,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/3647\/revisions\/3655"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=3647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=3647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=3647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}