{"id":2538,"date":"2010-10-20T10:56:28","date_gmt":"2010-10-20T08:56:28","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=2538"},"modified":"2015-10-16T12:55:10","modified_gmt":"2015-10-16T10:55:10","slug":"termoregolazione-ad-alta-temperatura","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/","title":{"rendered":"Termoregolazione ad alta temperatura"},"content":{"rendered":"<p>Vi sono dei processi produttivi legati al settore delle materie plastiche, che necessitano delle temperature di <a href=\"http:\/\/www.tempco.it\/soluzioni\/termoregolatori\/\">termoregolazione<\/a> molto elevate, nello specifico parlo di sistemi di riscaldamento e mantenimento della temperatura con <a href=\"http:\/\/www.tempco.it\/soluzioni\/package-unit\/centraline-di-termoregolazione-per-olio-diatermico\/\" target=\"_blank\">olio diatermico<\/a> fino a 350\u00b0C.<\/p>\n<p>Come si pu\u00f2 ben immaginare sono apparecchiature piuttosto sofisticate, in quanto a queste temperature anche la <a href=\"https:\/\/www.tempco.it\/blog\/2072\/olio-diatermico-ad-alta-temperatura-2\/\">componentistica<\/a> va selezionata con attenzione, come accennavo in <a href=\"https:\/\/www.tempco.it\/blog\/2049\/olio-diatermico-ad-alte-temperature\/\">precedenti articoli<\/a>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010009.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-thumbnail wp-image-2541\" title=\"pompa a trascinamento magnetico per olio diatermico ad alta temperatura\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010009-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Vi sono tutta una serie di dettagli che vanno presi in seria considerazione:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.tempco.it\/blog\/1097\/vaso-di-espansione-per-olio-diatermico\/\">vasi di espansione<\/a><\/li>\n<li>strumentazione<\/li>\n<li><a href=\"https:\/\/www.tempco.it\/blog\/2083\/impianti-ad-olio-diatermico-prevenire-i-rischi-di-incendio\/\">coibentazione<\/a><\/li>\n<li>tubazioni<\/li>\n<li>materiali impiagati<\/li>\n<li>connessioni fra tubi e con le utenze<\/li>\n<\/ul>\n<p>Tutti aspetti che se sottovalutati, compromettono seriamente la funzionalilt\u00e0 della centralina e dell&#8217;impianto produttivo.<\/p>\n<p>Un altro aspetto fondamentale che potrebbe pregiudicare il buon funzionamento del sistema \u00e8 legato allo sfiato dell&#8217;impianto dall&#8217;aria. Sembra una questione banale, ma posso affermare con certezza, che il 90% dei problemi che ci ritroviamo ad affrontare, soprattutto in fase di avviamenti di impianti ad olio diatermico, sono legati ad una non corretta gestione degli sfiati aria dell&#8217;impianto.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P10100071.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-thumbnail wp-image-2542\" title=\"T REG coibentazione e sfiati aria su centralina di termoregolazione olio diatermico\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P10100071-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Bisogna infatti tenere ben presente che l&#8217;olio non \u00e8 come l&#8217;acqua, quindi i tempi di sfiato sono dilatati. Inoltre i sistemi di sfiato vanno realizzati pensando all&#8217;olio diatermico.<\/p>\n<p>Un semplice ma efficace consiglio che ci sentiamo di dare \u00e8 quello di avviare la centralina di termoregolazione, a freddo e far girare la pompa di circolazione per un tempo piuttosto lungo, continuando a sfiatare l&#8217;aria presente.<\/p>\n<p>Quindi cominciare a far salire la temperatura fino a 100\u00b0C, continuando a verificare la presenza di aria e sfiatarla.<\/p>\n<p>Continuare con questo sistema di incremento di temperatura a step successivi, fino alla completa sicurezza di non avere pi\u00f9 aria presente nell&#8217;impianto, quindi e solo allora, partire con la centralina a pieno regime.<\/p>\n<p>Fatto un buono sfiato dell&#8217;aria, non si avranno pi\u00f9 problemi in seguito.<\/p>\n<p>Attenzione che delle bolle di aria in un circuito di olio diatermico ad alta temperatura, creano cavitazione, rigurgiti dal vaso di espansione, con conseguenza che lascio immaginare.<\/p>\n<p>&#8230;altro discorso se ci fosse anche acqua o umidit\u00e0 nell&#8217;olio, ma magari ne parlo prossimamente.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010024.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-thumbnail wp-image-2543\" title=\"centraline T REG per olio diatermico ad alta temperatura\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vi sono dei processi produttivi legati al settore delle materie plastiche, che necessitano delle temperature di termoregolazione molto elevate, nello [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[48,3,15,35],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Termoregolazione ad alta temperatura - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termoregolazione ad alta temperatura - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Vi sono dei processi produttivi legati al settore delle materie plastiche, che necessitano delle temperature di termoregolazione molto elevate, nello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-20T08:56:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-16T10:55:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010009-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Valter Biolchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valter Biolchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\"},\"author\":{\"name\":\"Valter Biolchi\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\"},\"headline\":\"Termoregolazione ad alta temperatura\",\"datePublished\":\"2010-10-20T08:56:28+00:00\",\"dateModified\":\"2015-10-16T10:55:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\"},\"wordCount\":333,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"articleSection\":[\"centraline di termoregolazione\",\"Energia Termica\",\"Termoregolazione\",\"termostatazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\",\"name\":\"Termoregolazione ad alta temperatura - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2010-10-20T08:56:28+00:00\",\"dateModified\":\"2015-10-16T10:55:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termoregolazione ad alta temperatura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\",\"name\":\"Valter Biolchi\",\"sameAs\":[\"http:\/\/www.tempco.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termoregolazione ad alta temperatura - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/","og_locale":"it_IT","og_type":"article","og_title":"Termoregolazione ad alta temperatura - Tempco Blog","og_description":"Vi sono dei processi produttivi legati al settore delle materie plastiche, che necessitano delle temperature di termoregolazione molto elevate, nello [&hellip;]","og_url":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2010-10-20T08:56:28+00:00","article_modified_time":"2015-10-16T10:55:10+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2010\/10\/P1010009-150x150.jpg"}],"author":"Valter Biolchi","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Valter Biolchi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/"},"author":{"name":"Valter Biolchi","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6"},"headline":"Termoregolazione ad alta temperatura","datePublished":"2010-10-20T08:56:28+00:00","dateModified":"2015-10-16T10:55:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/"},"wordCount":333,"commentCount":2,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"articleSection":["centraline di termoregolazione","Energia Termica","Termoregolazione","termostatazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/","url":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/","name":"Termoregolazione ad alta temperatura - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2010-10-20T08:56:28+00:00","dateModified":"2015-10-16T10:55:10+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/2538\/termoregolazione-ad-alta-temperatura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Termoregolazione ad alta temperatura"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6","name":"Valter Biolchi","sameAs":["http:\/\/www.tempco.it"]}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/2538"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=2538"}],"version-history":[{"count":5,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/2538\/revisions"}],"predecessor-version":[{"id":5333,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/2538\/revisions\/5333"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=2538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=2538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=2538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}