{"id":222,"date":"2008-02-25T18:43:18","date_gmt":"2008-02-25T16:43:18","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/"},"modified":"2019-07-26T12:53:01","modified_gmt":"2019-07-26T10:53:01","slug":"ricordatevi-dellantigelo-2","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/","title":{"rendered":"Ricordatevi dell&#8217;antigelo (2)"},"content":{"rendered":"<p>Dopo il post <a href=\"https:\/\/www.tempco.it\/blog\/165\/ricordatevi-dellantigelo\/\">ricordatevi dell&#8217;antigelo<\/a>, ho pensato di inserire un link alle soluzioni incongelabili tipicamente utilizzate nell&#8217;industria.<\/p>\n<p>Ho cercato di mettere insieme un po di dati significativi ed ecco qui la tabella:<\/p>\n<p><a href=\"https:\/\/www.tempco.it\/wp-content\/uploads\/2012\/12\/Temperature-di-congelamento_freezpoints.pdf\" target=\"_blank\" rel=\"noopener\">Temperature di congelamento soluzioni anticongelanti<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/02\/freeze.jpg\" alt=\"Freeze congelamento\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il post ricordatevi dell&#8217;antigelo, ho pensato di inserire un link alle soluzioni incongelabili tipicamente utilizzate nell&#8217;industria. Ho cercato di [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,6,13,4,12],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ricordatevi dell&#039;antigelo (2) - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricordatevi dell&#039;antigelo (2) - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Dopo il post ricordatevi dell&#8217;antigelo, ho pensato di inserire un link alle soluzioni incongelabili tipicamente utilizzate nell&#8217;industria. Ho cercato di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2008-02-25T16:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-26T10:53:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/02\/freeze.jpg\" \/>\n<meta name=\"author\" content=\"Valter Biolchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valter Biolchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\"},\"author\":{\"name\":\"Valter Biolchi\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\"},\"headline\":\"Ricordatevi dell&#8217;antigelo (2)\",\"datePublished\":\"2008-02-25T16:43:18+00:00\",\"dateModified\":\"2019-07-26T10:53:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\"},\"wordCount\":39,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"articleSection\":[\"Energia Termica\",\"Free cooling\",\"Manutenzione\",\"Raffreddamento\",\"Refrigeratori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\",\"name\":\"Ricordatevi dell'antigelo (2) - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2008-02-25T16:43:18+00:00\",\"dateModified\":\"2019-07-26T10:53:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricordatevi dell&#8217;antigelo (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\",\"name\":\"Valter Biolchi\",\"sameAs\":[\"http:\/\/www.tempco.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricordatevi dell'antigelo (2) - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/","og_locale":"it_IT","og_type":"article","og_title":"Ricordatevi dell'antigelo (2) - Tempco Blog","og_description":"Dopo il post ricordatevi dell&#8217;antigelo, ho pensato di inserire un link alle soluzioni incongelabili tipicamente utilizzate nell&#8217;industria. Ho cercato di [&hellip;]","og_url":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2008-02-25T16:43:18+00:00","article_modified_time":"2019-07-26T10:53:01+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/02\/freeze.jpg"}],"author":"Valter Biolchi","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Valter Biolchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/"},"author":{"name":"Valter Biolchi","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6"},"headline":"Ricordatevi dell&#8217;antigelo (2)","datePublished":"2008-02-25T16:43:18+00:00","dateModified":"2019-07-26T10:53:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/"},"wordCount":39,"commentCount":0,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"articleSection":["Energia Termica","Free cooling","Manutenzione","Raffreddamento","Refrigeratori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/","url":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/","name":"Ricordatevi dell'antigelo (2) - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2008-02-25T16:43:18+00:00","dateModified":"2019-07-26T10:53:01+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/222\/ricordatevi-dellantigelo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Ricordatevi dell&#8217;antigelo (2)"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6","name":"Valter Biolchi","sameAs":["http:\/\/www.tempco.it"]}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/222"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":1,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"predecessor-version":[{"id":7101,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/222\/revisions\/7101"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}