{"id":175,"date":"2008-01-18T19:11:49","date_gmt":"2008-01-18T17:11:49","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/"},"modified":"2008-02-13T22:54:15","modified_gmt":"2008-02-13T20:54:15","slug":"efficienza-e-risparmio-energetico","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/","title":{"rendered":"Efficienza e risparmio energetico"},"content":{"rendered":"<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/c000007.jpg\" title=\"piastre sporche\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/c000007.thumbnail.jpg\" alt=\"piastre sporche\" \/><\/a><\/p>\n<p><strong>Quando progetto un nuovo impianto<\/strong> oppure <strong>l&#8217;upgrade di un impianto esistente<\/strong>, in <strong><em>primo piano<\/em><\/strong> viene posto sempre e comunque il fattore <em><strong>risparmio energetico e la relativa efficienza<\/strong><\/em>.<\/p>\n<p>Questa \u00e8 una regola fondamentale e basilare nella progettazione moderna degli impianti.<\/p>\n<p>Quando poi vado a fare i rilievi in campo, mi ritrovo delle situazioni che stridono con quello che dovrei mettere in pratica, mi spiego meglio.<\/p>\n<p><em>Gli impianti di raffreddamento\/riscaldamento\/termoregolazione, sono impianti non produttivi, ovvero sono dei servizi ai processi produttivi.<\/em><\/p>\n<p>Spesso questi impianti, una volta installati vengono completamente dimenticati, anche dagli addetti alla manutenzione, che a causa di carichi di lavoro impegnativi e necessit\u00e0 di contrarre i costi si trovano nella difficile posizione di dover manutenere, spendendo poco ed impiegandoci pochissimo tempo.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/impianto-chimico.jpg\" title=\"impianto chimico\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/impianto-chimico.thumbnail.jpg\" alt=\"impianto chimico\" \/><\/a><\/p>\n<p>Questo porta a trovare sugli impianti spesso e volentieri dei problemi, semplici di volta in volta, ma strategici nella conduzione stessa dell&#8217;impianto:<\/p>\n<ul>\n<li>mancanza di pulizia delle superfici di scambio<\/li>\n<li>mancanza di sistemi adeguati di filtrazione (o non corretta gestione e\/o manutenzione)<\/li>\n<li>mancanza di sistemi di dosaggio di chemicals (o non corretta gestione)<\/li>\n<li>mancanza di manutenzione su supporti e\/o cuscinetti<\/li>\n<\/ul>\n<p>Gi\u00e0 questi tre semplici fattori, abbattono il rendimento di un impianto di raffreddamento, rendendo spesso vani gli sforzi fatti in fase di progetto per contenere il consumo energetico, incrementando l&#8217;assorbimento di energia elettrica a volte anche del 20-30%, per non parlare dei consumi di acqua.<\/p>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/filter_gea_tempco_pagina_02_immagine_0001.jpg\" title=\"sporcamento in uno scambiatore a piastre\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/filter_gea_tempco_pagina_02_immagine_0001.thumbnail.jpg\" alt=\"sporcamento in uno scambiatore a piastre\" \/><\/a><\/p>\n<p>Infatti risulta evidente come una mancanza di manutenzione che interessa il breve ed incompleto elenco di cui sopra, porti a:<\/p>\n<ul>\n<li>minore efficienza di scambio termico -&gt; maggiore potenzialit\u00e0 assorbite -&gt; maggiore consumo di energia elettrica<\/li>\n<li>sporcamento delle apparecchiature di scambio -&gt; maggiore potenzialit\u00e0 assorbite -&gt; maggiore consumo di energia elettrica<\/li>\n<li>sporcamento dei tubi di condensatori ad acqua di chiller -&gt; minore scambio, maggiore assorbimento di energia elettrica, maggiore consumo di acqua.<\/li>\n<li>maggiori attriti -&gt; maggiore potenzialit\u00e0 assorbite -&gt; maggiore consumo di energia elettrica<\/li>\n<li>rotture impreviste&#8230;e qui lascio spazio alla immaginazione<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/filter_gea_tempco_pagina_08_immagine_0001.jpg\" title=\"tipico filtro autopulente per scambiatori di calore\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/filter_gea_tempco_pagina_08_immagine_0001.thumbnail.jpg\" alt=\"tipico filtro autopulente per scambiatori di calore\" \/><\/a><\/p>\n<p>In definitiva:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.tempco.it\/download.asp?ID=93\">teniamo d&#8217;occhio i manuali di uso e manutenzione<\/a><\/li>\n<li>programmiamo una manutenzione che sia tale<\/li>\n<li>prevediamo dei filtri (magari autopulenti)<\/li>\n<li><a href=\"http:\/\/www.tempco.it\/prodotti.asp?ID=88\">prevediamo dei sistemi di trattamento dell&#8217;acqua<\/a><\/li>\n<li>manteniamo gli impianti che abbiamo in servizio<\/li>\n<\/ul>\n<p>&#8230;e nel caso non siate in grado, rivolgetevi a degli specialisti e chiedete supporto.<\/p>\n<p><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/manutenzione-programmata.jpg\" title=\"manutenzione programmata\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/manutenzione-programmata.thumbnail.jpg\" alt=\"manutenzione programmata\" \/><\/a><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/dscf0042.JPG\" title=\"scambiatore a fascio tubiero incrostato\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/dscf0042.thumbnail.JPG\" alt=\"scambiatore a fascio tubiero incrostato\" \/><\/a><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/addolcitore-duplex-2.jpg\" title=\"addolcitore\"><img decoding=\"async\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/addolcitore-duplex-2.thumbnail.jpg\" alt=\"addolcitore\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando progetto un nuovo impianto oppure l&#8217;upgrade di un impianto esistente, in primo piano viene posto sempre e comunque il [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,13,10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Efficienza e risparmio energetico - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Efficienza e risparmio energetico - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Quando progetto un nuovo impianto oppure l&#8217;upgrade di un impianto esistente, in primo piano viene posto sempre e comunque il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2008-01-18T17:11:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2008-02-13T20:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/c000007.thumbnail.jpg\" \/>\n<meta name=\"author\" content=\"Valter Biolchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valter Biolchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\"},\"author\":{\"name\":\"Valter Biolchi\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\"},\"headline\":\"Efficienza e risparmio energetico\",\"datePublished\":\"2008-01-18T17:11:49+00:00\",\"dateModified\":\"2008-02-13T20:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"articleSection\":[\"Energia Termica\",\"Manutenzione\",\"Risparmio energetico\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\",\"name\":\"Efficienza e risparmio energetico - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2008-01-18T17:11:49+00:00\",\"dateModified\":\"2008-02-13T20:54:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Efficienza e risparmio energetico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\",\"name\":\"Valter Biolchi\",\"sameAs\":[\"http:\/\/www.tempco.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Efficienza e risparmio energetico - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/","og_locale":"it_IT","og_type":"article","og_title":"Efficienza e risparmio energetico - Tempco Blog","og_description":"Quando progetto un nuovo impianto oppure l&#8217;upgrade di un impianto esistente, in primo piano viene posto sempre e comunque il [&hellip;]","og_url":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2008-01-18T17:11:49+00:00","article_modified_time":"2008-02-13T20:54:15+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2008\/01\/c000007.thumbnail.jpg"}],"author":"Valter Biolchi","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Valter Biolchi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/"},"author":{"name":"Valter Biolchi","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6"},"headline":"Efficienza e risparmio energetico","datePublished":"2008-01-18T17:11:49+00:00","dateModified":"2008-02-13T20:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"articleSection":["Energia Termica","Manutenzione","Risparmio energetico"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/","url":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/","name":"Efficienza e risparmio energetico - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2008-01-18T17:11:49+00:00","dateModified":"2008-02-13T20:54:15+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/175\/efficienza-e-risparmio-energetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Efficienza e risparmio energetico"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6","name":"Valter Biolchi","sameAs":["http:\/\/www.tempco.it"]}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/175"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":0,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}