{"id":1091,"date":"2009-04-06T10:28:54","date_gmt":"2009-04-06T08:28:54","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=1091"},"modified":"2018-10-26T13:14:58","modified_gmt":"2018-10-26T11:14:58","slug":"vaso-di-espansione","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/","title":{"rendered":"Vaso di espansione"},"content":{"rendered":"<p>Avevo precedentemente parlato di <a href=\"https:\/\/www.tempco.it\/blog\/197\/coefficiente-di-espansione-dellacqua\/\" target=\"_blank\" rel=\"noopener\">vasi di espansione<\/a> ed espansione dei fluidi riscaldati.<\/p>\n<p>Ogni tipologia di impianto necessita inevitabilmente di avere un sistema (<strong>Vaso, serbatoio<\/strong> o chiamatelo come volete), che permetta al <strong>fluido riscaldato di espandersi<\/strong>, senza mettere in pressione il circuito, o comunque <strong>senza che la pressione del circuito superi i valori di progetto<\/strong>, con conseguenza facilmente immaginabili.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2235.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-thumbnail wp-image-1093 aligncenter\" title=\"gruppo di pompaggio con vaso di espansione chiuso a membrana\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2235-150x150.jpg\" alt=\"gruppo di pompaggio con vaso di espansione chiuso a membrana\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><!--more-->Negli impianti civili di distribuzione dell&#8217;acqua, solitamente nelle caldaie, sono presenti i vasi di espansione a membrana, precaricati. Quando la potenzialit\u00e0 e la dimensione dell&#8217;impianto diventano elevati, questi vasi lasciano il posto a veri e propri serbatoi completi di compressore d&#8217;aria per la relativa pressurizzazione. Negli impianti ad <a href=\"https:\/\/www.tempco.it\/blog\/5888\/durata-olio-diatermico-nelle-centraline\/\" target=\"_blank\" rel=\"noopener\">olio diatermico<\/a>, dove i valori di espansione del fluido vettore (olio diatermico appunto) sono importanti, la progettazione, la realizzazione e l&#8217;installazione del vaso di espansione diventa una fase progettuale che richiede parecchia attenzione.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf3237.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-thumbnail wp-image-1094 aligncenter\" title=\"vaso di espansione su centralina ad olio diatermico\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf3237-150x150.jpg\" alt=\"vaso di espansione su centralina ad olio diatermico\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Tutte queste applicazioni meritano sicuramente una attenzione particolare, che dedicheremo prossimamente.<\/p>\n<p>Volevo richiamare la vostra attenzione, sui dei <a href=\"https:\/\/www.tempco.it\/soluzioni\/raffreddatori-industriali-elettroradiatori\/t-fin-accessori\/\" target=\"_blank\" rel=\"noopener\">vasi di espansione<\/a> particolari, quelli cio\u00e8 abbinati ai sistemi di <strong>cogenerazione con motori endotermici,<\/strong> che richiedono una serie di caratteristiche interessanti.<\/p>\n<p>In pratica come tutti i motori, c&#8217;\u00e8 la necessit\u00e0 di poter lavorare con il fluido di raffreddamento in leggera sovrapressione (0,7 bar tipicamente), per permettere al fluido stesso di superare la fatidica soglia dei 100\u00b0C, senza problemi&#8230; al tempo stesso per\u00f2 non bisogna permettere che il livello di temperatura diventi troppo elevato, causando la &#8220;cottura&#8221; del motore.<\/p>\n<p>A questo scopo, i <a href=\"http:\/\/www.tempco.it\/prodotti.asp?ID=19&amp;ID2=102\">v<\/a><a href=\"https:\/\/www.tempco.it\/soluzioni\/cogenerazione\/\" target=\"_blank\" rel=\"noopener\">asi di espansione dedicati agli impianti di cogenerazione<\/a> con motore endotermico, sono equipaggiati con dei tappi particolari, che tengono la pressione fino ad un determinato livello (0,7 bar appunto), dopodich\u00e8 hanno una apertura a molla, che fa sfiatare il circuito, prevenendo eventuali danni o sovratemperature&#8230; di solito a quel punto interviene qualche &#8220;RED LIGHT&#8221; a segnalare il problema.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2680.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-thumbnail wp-image-1095 aligncenter\" title=\"Indicatore di livello, livellostati, connessioni vaso di espansione per motore endotermico\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2680-150x150.jpg\" alt=\"Indicatore di livello, livellostati, connessioni vaso di espansione per motore endotermico\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>A corredo vengono forniti anche livelli visivi e livellostati di sicurezza, per segnalare la mancanza di fluido refrigerante.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2679.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-thumbnail wp-image-1092 aligncenter\" title=\"classico tappo radiatore per vaso di espansione per motore endotermico\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2679-150x150.jpg\" alt=\"classico tappo radiatore per vaso di espansione per motore endotermico\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avevo precedentemente parlato di vasi di espansione ed espansione dei fluidi riscaldati. Ogni tipologia di impianto necessita inevitabilmente di avere [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,3,19,20,33,37],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vaso di espansione - Tempco Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaso di espansione - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Avevo precedentemente parlato di vasi di espansione ed espansione dei fluidi riscaldati. Ogni tipologia di impianto necessita inevitabilmente di avere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-06T08:28:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-26T11:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2235-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Valter Biolchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valter Biolchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\"},\"author\":{\"name\":\"Valter Biolchi\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\"},\"headline\":\"Vaso di espansione\",\"datePublished\":\"2009-04-06T08:28:54+00:00\",\"dateModified\":\"2018-10-26T11:14:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"articleSection\":[\"elettroradiatori\",\"Energia Termica\",\"Free cooler\",\"Installazione\",\"olio idraulico e lubrificanti\",\"Termotecnica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\",\"name\":\"Vaso di espansione - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2009-04-06T08:28:54+00:00\",\"dateModified\":\"2018-10-26T11:14:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaso di espansione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6\",\"name\":\"Valter Biolchi\",\"sameAs\":[\"http:\/\/www.tempco.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaso di espansione - Tempco Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/","og_locale":"it_IT","og_type":"article","og_title":"Vaso di espansione - Tempco Blog","og_description":"Avevo precedentemente parlato di vasi di espansione ed espansione dei fluidi riscaldati. Ogni tipologia di impianto necessita inevitabilmente di avere [&hellip;]","og_url":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2009-04-06T08:28:54+00:00","article_modified_time":"2018-10-26T11:14:58+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2009\/03\/dscf2235-150x150.jpg"}],"author":"Valter Biolchi","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Valter Biolchi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/"},"author":{"name":"Valter Biolchi","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6"},"headline":"Vaso di espansione","datePublished":"2009-04-06T08:28:54+00:00","dateModified":"2018-10-26T11:14:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"articleSection":["elettroradiatori","Energia Termica","Free cooler","Installazione","olio idraulico e lubrificanti","Termotecnica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/","url":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/","name":"Vaso di espansione - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2009-04-06T08:28:54+00:00","dateModified":"2018-10-26T11:14:58+00:00","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/1091\/vaso-di-espansione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Vaso di espansione"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/4f3ef872222fd5187b9ae2d83dc5afa6","name":"Valter Biolchi","sameAs":["http:\/\/www.tempco.it"]}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/1091"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=1091"}],"version-history":[{"count":5,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/1091\/revisions"}],"predecessor-version":[{"id":6554,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/1091\/revisions\/6554"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=1091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=1091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=1091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}