{"id":10698,"date":"2025-09-04T10:56:11","date_gmt":"2025-09-04T08:56:11","guid":{"rendered":"https:\/\/www.tempco.it\/blog\/?p=10698"},"modified":"2025-09-04T10:56:11","modified_gmt":"2025-09-04T08:56:11","slug":"scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano","status":"publish","type":"post","link":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/","title":{"rendered":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano"},"content":{"rendered":"<p><strong>Tempco<\/strong> partecipa con <a href=\"https:\/\/www.microchannel-devices.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Microchannel Devices<\/strong><\/a> alla edizione di <a href=\"https:\/\/www.gastechevent.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Gastech 2025<\/strong><\/a>, che si terr\u00e0 <strong>dal 9 al 12 settembre in Fiera Milano<\/strong>, dove porteremo i nostri <a href=\"https:\/\/pche.it\/\" target=\"_blank\" rel=\"noopener\"><strong>scambiatori PCHE<\/strong><\/a> per applicazioni nella filiera dell\u2019<strong><a href=\"https:\/\/www.tempco.it\/blog\/10389\/idrogeno-scambiatori-pche-compatti-ed-efficienti-nella-mobilita-green\/\" target=\"_blank\" rel=\"noopener\">idrogeno<\/a><\/strong> e altre tecnologie innovative per l\u2019energia pulita.<\/p>\n<p>Gastech \u00e8 il principale evento internazionale dedicato alle tecnologie per il <strong>gas naturale<\/strong>, l\u2019<strong>idrogeno<\/strong>, la <strong>cattura del carbonio<\/strong> e la <strong>transizione energetica<\/strong>. La manifestazione per quattro giorni funger\u00e0 da punto di incontro per 50.000 professionisti dell\u2019energia, provenienti da oltre 150 Paesi, ospitando le novit\u00e0 e soluzioni tecnologiche pi\u00f9 all\u2019avanguardia di oltre 1.000 espositori e 1.000 esperti del settore. Il tutto per creare un dinamico ecosistema focalizzato su <strong>innovazione green e sostenibilit\u00e0 energetica<\/strong>.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-10701\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas.jpg\" alt=\"Immagine illustrativa della partecipazione di Tempco e Microchannel Devices alla Gastech 2025 di Milano \" width=\"450\" height=\"396\" srcset=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas.jpg 800w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas-300x264.jpg 300w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas-768x675.jpg 768w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Microchannel Devices con Tempco presenter\u00e0 nel proprio spazio le <strong>soluzioni <a href=\"https:\/\/www.tempco.it\/soluzioni\/scambiatori-di-calore\/scambiatori-pche\/\" target=\"_blank\" rel=\"noopener\">PCHE<\/a> per lo scambio termico<\/strong>, progettate per applicazioni ad alta efficienza in ambienti critici. Il particolare processo di produzione per <a href=\"https:\/\/www.tempco.it\/blog\/9805\/diffusion-bonding-per-scambiatori-di-calore-ad-altissime-prestazioni\/\" target=\"_blank\" rel=\"noopener\"><strong>diffusion bonding<\/strong><\/a> consente infatti a questi scambiatori di offrire una eccellente resistenza a livelli di temperatura e pressione estremi. Il metodo di <a href=\"https:\/\/www.tempco.it\/blog\/10367\/tempco-presenta-il-nuovo-sito-dedicato-agli-innovativi-scambiatori-pche\/\" target=\"_blank\" rel=\"noopener\"><strong>chemical etching<\/strong><\/a> impiegato per realizzare i circuiti di scambio termico sulle piastre degli scambiatori permette invece di ottenere soluzioni ad altissima efficienza di scambio e customizzate sulle specifiche esigenze di processo, anche in <a href=\"https:\/\/www.tempco.it\/blog\/10558\/scambiatori-pche-soluzione-multi-stream-per-raffreddamento-interstadio\/\" target=\"_blank\" rel=\"noopener\">modalit\u00e0 multi stream<\/a> per raffreddamento interstadio.<\/p>\n<p>In mostra allo stand MCD sar\u00e0 inoltre possibile vedere un modello in scala dello scambiatore PCHE realizzato per <a href=\"https:\/\/www.rosetti.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Rosetti Marino<\/strong><\/a>, primo esempio di scambiatore PCHE realizzato per <a href=\"https:\/\/www.tempco.it\/blog\/10399\/scambiatore-pche-in-applicazioni-di-raffreddamento-oilgas-offshore\/\" target=\"_blank\" rel=\"noopener\">lethal service per il settore oil &amp; gas<\/a>, gi\u00e0 installato su piattaforma offshore.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-10703\" src=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices.jpg\" alt=\"Immagine che mostra lo scambiatore PCHE realizzato da Tempco e Microchannel Devices per Rosetti Marino in lethal service per il settore oil &amp; gas \" width=\"560\" height=\"425\" srcset=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices.jpg 1587w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices-300x228.jpg 300w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices-1024x778.jpg 1024w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices-768x583.jpg 768w, https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-PCHE-Rosetti-gastech-Microchannel-Devices-1536x1166.jpg 1536w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>Tempco vi aspetta a <strong>Gastech a Milano<\/strong>, presso lo stand Microchannel Devices al <strong>Pad. 18, spazio I110<\/strong>, per illustrare tutte le potenzialit\u00e0 e i vantaggi offerti dagli scambiatori PCHE per applicazioni a elevatissime prestazioni nel comparto della <strong>Green Energy<\/strong>, dell\u2019<strong>ingegneria termica avanzata<\/strong> e dell\u2019integrazione nei <strong>sistemi Oil &amp; gas del futuro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempco partecipa con Microchannel Devices a Gastech 2025 a Milano, dal 9 al 12 settembre, presentando le soluzioni con scambiatori PCHE ad altissima efficienza di scambio termico per applicazioni nei comparti idrogeno e oil &#038; gas.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,4,49,15],"tags":[1451,4281,3771,119,144,4482,745,2946,3844,4421,3498,547,3841,118,4387,4483,204,122,3933,291,698,3922,3923],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog<\/title>\n<meta name=\"description\" content=\"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil &amp; gas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog\" \/>\n<meta property=\"og:description\" content=\"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil &amp; gas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempco Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tempco.srl\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T08:56:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas.jpg\" \/>\n<meta name=\"author\" content=\"Marco Zambelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:site\" content=\"@Tempco_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Zambelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\"},\"author\":{\"name\":\"Marco Zambelli\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\"},\"headline\":\"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano\",\"datePublished\":\"2025-09-04T08:56:11+00:00\",\"dateModified\":\"2025-09-04T08:56:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"keywords\":[\"applicazioni critiche\",\"chemical etching\",\"diffusion bonding\",\"efficienza energetica\",\"energia\",\"Gastech\",\"green energy\",\"idrogeno\",\"Microchannel Devices\",\"multi-stream\",\"offshore\",\"oil &amp; gas\",\"PCHE\",\"raffreddamento\",\"raffreddamento multistadio\",\"Rosetti Marino\",\"scambiatori\",\"scambio termico\",\"solid sustainability\",\"sostenibilit\u00e0\",\"Tempco\",\"Tempco Green\",\"transizione energetica\"],\"articleSection\":[\"Energia Termica\",\"Raffreddamento\",\"Scambiatori a piastre\",\"Termoregolazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\",\"name\":\"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\"},\"datePublished\":\"2025-09-04T08:56:11+00:00\",\"dateModified\":\"2025-09-04T08:56:11+00:00\",\"description\":\"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil & gas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tempco.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#website\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"name\":\"Tempco Blog\",\"description\":\"Soluzioni per l&#039;energia termica\",\"publisher\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempco.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#organization\",\"name\":\"Tempco Srl\",\"url\":\"https:\/\/www.tempco.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"contentUrl\":\"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg\",\"width\":317,\"height\":317,\"caption\":\"Tempco Srl\"},\"image\":{\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tempco.srl\",\"https:\/\/twitter.com\/Tempco_it\",\"https:\/\/www.youtube.com\/c\/TempcoItalia\",\"https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/\",\"https:\/\/www.instagram.com\/tempco_solidtemperature\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4\",\"name\":\"Marco Zambelli\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog","description":"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil & gas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/","og_locale":"it_IT","og_type":"article","og_title":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog","og_description":"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil & gas.","og_url":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/","og_site_name":"Tempco Blog","article_publisher":"https:\/\/www.facebook.com\/tempco.srl","article_published_time":"2025-09-04T08:56:11+00:00","og_image":[{"url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2025\/09\/Tempco-Microchannel-Devices-Gastech-2025-Milano-PCHE-oil-and-gas.jpg"}],"author":"Marco Zambelli","twitter_card":"summary_large_image","twitter_creator":"@Tempco_it","twitter_site":"@Tempco_it","twitter_misc":{"Scritto da":"Marco Zambelli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#article","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/"},"author":{"name":"Marco Zambelli","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4"},"headline":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano","datePublished":"2025-09-04T08:56:11+00:00","dateModified":"2025-09-04T08:56:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"keywords":["applicazioni critiche","chemical etching","diffusion bonding","efficienza energetica","energia","Gastech","green energy","idrogeno","Microchannel Devices","multi-stream","offshore","oil &amp; gas","PCHE","raffreddamento","raffreddamento multistadio","Rosetti Marino","scambiatori","scambio termico","solid sustainability","sostenibilit\u00e0","Tempco","Tempco Green","transizione energetica"],"articleSection":["Energia Termica","Raffreddamento","Scambiatori a piastre","Termoregolazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/","url":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/","name":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano - Tempco Blog","isPartOf":{"@id":"https:\/\/www.tempco.it\/blog\/#website"},"datePublished":"2025-09-04T08:56:11+00:00","dateModified":"2025-09-04T08:56:11+00:00","description":"Tempco partecipa con Microchannel Devices alla Gastech 2025 a Milano, presentando le soluzioni con scambiatori PCHE per idrogeno e oil & gas.","breadcrumb":{"@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempco.it\/blog\/10698\/scambiatori-pche-per-la-transizione-energetica-alla-gastech-2025-di-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tempco.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Scambiatori PCHE per la transizione energetica alla Gastech 2025 di Milano"}]},{"@type":"WebSite","@id":"https:\/\/www.tempco.it\/blog\/#website","url":"https:\/\/www.tempco.it\/blog\/","name":"Tempco Blog","description":"Soluzioni per l&#039;energia termica","publisher":{"@id":"https:\/\/www.tempco.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempco.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tempco.it\/blog\/#organization","name":"Tempco Srl","url":"https:\/\/www.tempco.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","contentUrl":"https:\/\/www.tempco.it\/blog\/wp-content\/uploads\/2022\/12\/logo_big.jpg","width":317,"height":317,"caption":"Tempco Srl"},"image":{"@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tempco.srl","https:\/\/twitter.com\/Tempco_it","https:\/\/www.youtube.com\/c\/TempcoItalia","https:\/\/www.linkedin.com\/company\/tempcoitaly\/about\/","https:\/\/www.instagram.com\/tempco_solidtemperature\/"]},{"@type":"Person","@id":"https:\/\/www.tempco.it\/blog\/#\/schema\/person\/7b9316f2ae038cf675b9efcabca742f4","name":"Marco Zambelli"}]}},"_links":{"self":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/10698"}],"collection":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/comments?post=10698"}],"version-history":[{"count":3,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/10698\/revisions"}],"predecessor-version":[{"id":10705,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/posts\/10698\/revisions\/10705"}],"wp:attachment":[{"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/media?parent=10698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/categories?post=10698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tempco.it\/blog\/wp-json\/wp\/v2\/tags?post=10698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}